{"id":986,"date":"2010-08-22T15:36:17","date_gmt":"2010-08-22T13:36:17","guid":{"rendered":"http:\/\/tikopia.wordpress.com\/2010\/08\/22\/visages-nrb\/"},"modified":"2010-08-22T15:36:17","modified_gmt":"2010-08-22T13:36:17","slug":"visages-nrb","status":"publish","type":"post","link":"http:\/\/www.xaviergalaup.net\/tikopia\/2010\/08\/visages-nrb\/","title":{"rendered":"Visages N&rsquo;r&rsquo;B"},"content":{"rendered":"<p>J&rsquo;attends chaque fois avec un fol espoir<br \/>que ces corps dansent<br \/>de la belle virevolte qui bouillonne<br \/>J&rsquo;entends chaque fois avec une belle acuit\u00e9<br \/>musique, cris, murmures, scherzo,<br \/>qui font vibrer ces visages en N&rsquo;r&rsquo;B<br \/>J&rsquo;entends chaque fois avec un beau frisson<br \/>le soupir doucement heureux<br \/>d&rsquo;un visiteur stopp\u00e9 net par une photo<br \/>J&rsquo;attends chaque fois avec une douloureuse impatience<br \/>l&rsquo;instant intime de la fermeture<br \/>o\u00f9 j&rsquo;\u00e9teins une \u00e0 une ces sc\u00e8nes de joie.<\/p>\n<p><i>d&rsquo;apr\u00e8s le photoblog <a target=\"_blank\" href=\"http:\/\/www.presence-urbaine.com\/\">Pr\u00e9sence Urbaine &#8211; Mister Hoveeto<\/a>, inspir\u00e9 de la photo <a target=\"_blank\" href=\"http:\/\/www.presence-urbaine.com\/index.php?showimage=128\">Lisette Model<\/a><\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>J&rsquo;attends chaque fois avec un fol espoirque ces corps dansentde la belle virevolte qui bouillonneJ&rsquo;entends chaque fois avec une belle acuit\u00e9musique, cris, murmures, scherzo,qui font vibrer ces visages en N&rsquo;r&rsquo;BJ&rsquo;entends chaque fois avec un beau frissonle soupir doucement heureuxd&rsquo;un visiteur stopp\u00e9 net par une photoJ&rsquo;attends chaque fois avec une douloureuse impatiencel&rsquo;instant intime de la fermetureo\u00f9 &hellip; <\/p>\n<p class=\"link-more\"><a href=\"http:\/\/www.xaviergalaup.net\/tikopia\/2010\/08\/visages-nrb\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Visages N&rsquo;r&rsquo;B&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[19,21,22,23,24,26],"tags":[],"jetpack_featured_media_url":"","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5H0vD-fU","jetpack-related-posts":[{"id":867,"url":"http:\/\/www.xaviergalaup.net\/tikopia\/2009\/04\/brouillard-metallique\/","url_meta":{"origin":986,"position":0},"title":"Brouillard m\u00e9tallique","date":"5 avril 2009","format":false,"excerpt":"prendre la route sans conviction, je flotte dans ces matins brumeux, ces matins ni tout \u00e0 fait les m\u00eames ni tout \u00e0 fait diff\u00e9rents, le go\u00fbt amer du sempiternel caf\u00e9, toujours le m\u00eame, chaque fois je traverse le pont, je suis saisis par le fol espoir -indicible- qu'il s'\u00e9croule, qu'une\u2026","rel":"","context":"Dans &quot;photos&quot;","img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":860,"url":"http:\/\/www.xaviergalaup.net\/tikopia\/2009\/03\/paperoles\/","url_meta":{"origin":986,"position":1},"title":"Paperoles","date":"22 mars 2009","format":false,"excerpt":"Je lutte contre la s\u00e8cheresse de mon corps en buvant sans arr\u00eat du th\u00e9, jasmin, wu-long, lampsong-souchan, darjeling, assam et th\u00e9 vert de toutes origines mais jamais le pur-ehr. Ce go\u00fbt de purin \u00e9coeure mes papilles. J'ai peur de mourir d\u00e9shydrat\u00e9 (12) Je regarde le ciel, le temps de tourner\u2026","rel":"","context":"Dans &quot;inspirations diverses&quot;","img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":871,"url":"http:\/\/www.xaviergalaup.net\/tikopia\/2009\/04\/histoire-urbaine\/","url_meta":{"origin":986,"position":2},"title":"Histoire urbaine","date":"10 avril 2009","format":false,"excerpt":"Je ne veux pas disparaitre comme ces silhouettes qui passent (et tr\u00e9passent?) devant mes yeux. Je marche, j'attends et je cherche une expression, un visage, un corps qui d\u00e9sire de la couleur. L'exub\u00e9rance architecturale me fait plus vibrer que le pas press\u00e9 des passants. Je photographie discr\u00e8tement \u00e0 la vol\u00e9e\u2026","rel":"","context":"Dans &quot;micro-fictions&quot;","img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":705,"url":"http:\/\/www.xaviergalaup.net\/tikopia\/2007\/06\/danse-des-sens\/","url_meta":{"origin":986,"position":3},"title":"Danse des sens","date":"17 juin 2007","format":false,"excerpt":"Je regarde tous ces visages de toi nostalgie de ta\u00a0\u00a0 \u00a0\u00a0 bouche Je regarde tous ces mots de toi nostalgie de tes\u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 murmures Je regarde tous ces habits de toi nostalgie de tes courbes Je regarde toutes ces photos de toi nostalgie de ton insouciance Je regarde toutes\u2026","rel":"","context":"Dans &quot;photos&quot;","img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2270,"url":"http:\/\/www.xaviergalaup.net\/tikopia\/2013\/04\/quand-le-tourbillon-est-parti-jai-su-ce-qui-manquait\/","url_meta":{"origin":986,"position":4},"title":"quand le tourbillon est parti j\u2019ai su ce qui manquait","date":"13 avril 2013","format":false,"excerpt":"Longtemps je me suis assis au milieu des chapeaux, et d\u00e8s qu\u2019il y avait du soleil je sortais prendre l\u2019air, attendre le chaland, quand j\u2019\u00e9tais fatigu\u00e9 alors je prenais une chaise et je me posais au milieu de chapeaux, j\u2019avais rep\u00e9r\u00e9 que c\u2019\u00e9tait l\u2019endroit strat\u00e9gique pour voir ces dames faire\u2026","rel":"","context":"Dans &quot;fragment po\u00e9tique&quot;","img":{"alt_text":"","src":"https:\/\/i1.wp.com\/ssl11.ovh.net\/~xaviergada\/tikopia\/wp-content\/uploads\/2013\/04\/Chapeaux-249x300.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":940,"url":"http:\/\/www.xaviergalaup.net\/tikopia\/2009\/10\/falaises\/","url_meta":{"origin":986,"position":5},"title":"Falaises","date":"31 octobre 2009","format":false,"excerpt":"La plus belle ville du monde ne peut donner que cette immense sensation de solitude, le strass des lumi\u00e8res, les courbes des monuments, tout le pass\u00e9 qui p\u00e8se au coin de chaque rue historique, les belles oeuvres d'art qui nous font de l'oeil, rien n'y fait, quand ce petit quelque\u2026","rel":"","context":"Dans &quot;photos&quot;","img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/posts\/986"}],"collection":[{"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/comments?post=986"}],"version-history":[{"count":0,"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/posts\/986\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/media?parent=986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/categories?post=986"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/tags?post=986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}