{"id":982,"date":"2010-07-18T12:13:30","date_gmt":"2010-07-18T10:13:30","guid":{"rendered":"http:\/\/tikopia.wordpress.com\/2010\/07\/18\/ma-ville-est-vide\/"},"modified":"2010-07-18T12:13:30","modified_gmt":"2010-07-18T10:13:30","slug":"ma-ville-est-vide","status":"publish","type":"post","link":"http:\/\/www.xaviergalaup.net\/tikopia\/2010\/07\/ma-ville-est-vide\/","title":{"rendered":"Ma ville est vide"},"content":{"rendered":"<p>Ma ville est vide, ce n&rsquo;est pas une explosion nucl\u00e9aire ou autres catastrophes, ce n&rsquo;est pas un jour f\u00e9ri\u00e9, ce n&rsquo;est pas l&rsquo;heure creuse o\u00f9 tout s&rsquo;absente sans qu&rsquo;on ne sache pourquoi, ce n&rsquo;est pas une \u00e9vacuation pr\u00e9ventive face \u00e0 une intemp\u00e9rie majeure, ce n&rsquo;est pas un montage, c&rsquo;est mon crime qui m&rsquo;enl\u00e8ve toute vie int\u00e9rieure, la culpabilit\u00e9 efface toute pr\u00e9sence humaine, une parano\u00efa pouss\u00e9 tellement loin que m\u00eame mes yeux se jouent de moi, ce vide insens\u00e9 visant \u00e0 vouloir me faire basculer dans la folie alors que c&rsquo;est aux autres de dispara\u00eetre, ce serait si bon d&rsquo;\u00eatre le seul homme en vie avec tout \u00e0 moi, pour moi et \u00e0 cause de moi, devenir le ma\u00eetre du monde pouvant faire cesser tous ces sons absurdes qui ne font rien que contredire ce que je vois et ce que je veux, non, non, non, je ne peux pas penser sans le silence absolu.<\/p>\n<p><i>d&rsquo;apr\u00e8s les photos de <a target=\"_blank\" href=\"http:\/\/mlogue.com\/\">Matt Logue<\/a>, inspir\u00e9 de la photo <a target=\"_blank\" href=\"http:\/\/mlogue.com\/p586914549\/h72793c4#hadb7280\">Untitled #46<\/a> de la s\u00e9rie Empty L.A.<\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ma ville est vide, ce n&rsquo;est pas une explosion nucl\u00e9aire ou autres catastrophes, ce n&rsquo;est pas un jour f\u00e9ri\u00e9, ce n&rsquo;est pas l&rsquo;heure creuse o\u00f9 tout s&rsquo;absente sans qu&rsquo;on ne sache pourquoi, ce n&rsquo;est pas une \u00e9vacuation pr\u00e9ventive face \u00e0 une intemp\u00e9rie majeure, ce n&rsquo;est pas un montage, c&rsquo;est mon crime qui m&rsquo;enl\u00e8ve toute vie &hellip; <\/p>\n<p class=\"link-more\"><a href=\"http:\/\/www.xaviergalaup.net\/tikopia\/2010\/07\/ma-ville-est-vide\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Ma ville est vide&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[14,19,27,29],"tags":[],"jetpack_featured_media_url":"","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5H0vD-fQ","jetpack-related-posts":[{"id":857,"url":"http:\/\/www.xaviergalaup.net\/tikopia\/2009\/03\/recherche-souvenirs\/","url_meta":{"origin":982,"position":0},"title":"Recherche souvenirs","date":"9 mars 2009","format":false,"excerpt":"J'erre dans une ville, -ce n'est pas un r\u00eave-, je cherche un souvenir, ma m\u00e9moire est hant\u00e9e, -pas un r\u00eave- , je vois cette cath\u00e9drale majestueuse, blanche comme la mort, -pas un r\u00eave-, je peux respirer la joie des habitants qui passent ou attendent la nuit, -pas un r\u00eave-, moi\u2026","rel":"","context":"Dans &quot;photos&quot;","img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":689,"url":"http:\/\/www.xaviergalaup.net\/tikopia\/2007\/03\/micro-fictions-3\/","url_meta":{"origin":982,"position":1},"title":"micro-fictions 3","date":"27 mars 2007","format":false,"excerpt":"1\/ Chez le dentiste Impossible de tenir en place. J'imagine ce que le dentiste est en train de faire \u00e0 la jolie jeune fille avant moi. Elle n'est rest\u00e9e que quelques instants mais j'ai aim\u00e9 sa m\u00e8che en bataille devant son visage pench\u00e9 sur une revue people. Elle \u00e9tait calme\u2026","rel":"","context":"Dans &quot;inspirations diverses&quot;","img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":674,"url":"http:\/\/www.xaviergalaup.net\/tikopia\/2007\/02\/micro-fictions\/","url_meta":{"origin":982,"position":2},"title":"micro-fictions","date":"22 f\u00e9vrier 2007","format":false,"excerpt":"1\/ La gare J'attends devant le panneau d'affichage. Le brouhaha du retard r\u00e9sonne autour de moi. La foule est tendue d'impatience. Le ballet des hommes-valises s'est suspendu plein de menaces. Une petite fille rieuse serpente avec sa poup\u00e9e, chatouillant les pantalons, les robes, les bagages et les murs. Elle sarabande\u2026","rel":"","context":"Dans &quot;inspirations diverses&quot;","img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":909,"url":"http:\/\/www.xaviergalaup.net\/tikopia\/2009\/06\/crunch\/","url_meta":{"origin":982,"position":3},"title":"Crunch","date":"16 juin 2009","format":false,"excerpt":"Le futur s'\u00e9croule dans ma t\u00eate, je ne comprends plus rien, le paysage qui m'entoure est \u00e9trange, que fais-je ici loin de chez moi, loin de mon travail, est-ce que je fuis, ma vie est vide,\u00a0 le travail m'oblige \u00e0 r\u00e9p\u00e9ter une litanie douloureuse, plus d'argent, plus de travail, vous\u2026","rel":"","context":"Dans &quot;micro-fictions&quot;","img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2244,"url":"http:\/\/www.xaviergalaup.net\/tikopia\/2013\/03\/blanc-vitrail\/","url_meta":{"origin":982,"position":4},"title":"Blanc vitrail","date":"29 mars 2013","format":false,"excerpt":"J\u2019ai peur de sortir, mes mains sont rouges et tout m\u2019accuse, dehors ils sont tous hostiles, m\u00eame si je suis en paix maintenant, \u00e0 l\u2019abri de l\u2019enveloppe ouat\u00e9e de ce vitrail, de sa tension blanche qui apaise et redonne le sourire, les \u00e9v\u00e8nements se sont pr\u00e9cipit\u00e9s \u00e0 une vitesse incroyable,\u2026","rel":"","context":"Dans &quot;fragments d'une histoire&quot;","img":{"alt_text":"","src":"https:\/\/i1.wp.com\/ssl11.ovh.net\/~xaviergada\/tikopia\/wp-content\/uploads\/2013\/03\/Conques-225x300.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1477,"url":"http:\/\/www.xaviergalaup.net\/tikopia\/2012\/04\/il-y-avait-des-reveries\/","url_meta":{"origin":982,"position":5},"title":"il y avait des r\u00eaveries","date":"14 avril 2012","format":false,"excerpt":"Il y avait des r\u00eaveries qu\u2019on ne ma\u00eetrise pas, quand je marche \u00e0 l\u2019aube dans Montr\u00e9al vide et que je m\u2019imagine dans une autre ville plus belle, plus sensuelle, plus lumineuse, les images se d\u00e9roulent sans se superposer, je me vois \u00e0 une fen\u00eatre et le beau temps m\u2019emp\u00eache de\u2026","rel":"","context":"Dans &quot;fragment po\u00e9tique&quot;","img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/posts\/982"}],"collection":[{"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/comments?post=982"}],"version-history":[{"count":0,"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/posts\/982\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/media?parent=982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/categories?post=982"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/tags?post=982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}