{"id":963,"date":"2010-02-28T18:03:00","date_gmt":"2010-02-28T17:03:00","guid":{"rendered":"http:\/\/tikopia.wordpress.com\/?p=633"},"modified":"2010-02-28T18:03:00","modified_gmt":"2010-02-28T17:03:00","slug":"souffle-flou","status":"publish","type":"post","link":"http:\/\/www.xaviergalaup.net\/tikopia\/2010\/02\/souffle-flou\/","title":{"rendered":"Souffle flou"},"content":{"rendered":"<p>Un souffle flou n&rsquo;apaise pas les \u00e2mes perdues.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un souffle flou n&rsquo;apaise pas les \u00e2mes perdues.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[20],"tags":[],"jetpack_featured_media_url":"","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5H0vD-fx","jetpack-related-posts":[{"id":2145,"url":"http:\/\/www.xaviergalaup.net\/tikopia\/2012\/12\/je-suis-flou-et-il-suffirait-de-pas-grand-chose-pour-que-je-menvole\/","url_meta":{"origin":963,"position":0},"title":"je suis flou et il suffirait de pas grand chose pour que je m\u2019envole","date":"2 d\u00e9cembre 2012","format":false,"excerpt":"D\u00e8s que le temps le permet, j\u2019enfile mes chaussures de marche et je vais tra\u00eener sur le chemin des douaniers. Les plages, les falaises, la c\u00f4te sont toujours belles quelque soit la m\u00e9t\u00e9o. Je marche longtemps mais je prends mon temps et je m\u2019arr\u00eate souvent. Je regarde, j\u2019observe, je m'impr\u00e8gne,\u2026","rel":"","context":"Dans &quot;fragment po\u00e9tique&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ssl11.ovh.net\/~xaviergada\/tikopia\/wp-content\/uploads\/2012\/12\/Cl\u00c3\u00a9Plage.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":984,"url":"http:\/\/www.xaviergalaup.net\/tikopia\/2010\/08\/je-vois-flou\/","url_meta":{"origin":963,"position":1},"title":"Je vois flou","date":"21 ao\u00fbt 2010","format":false,"excerpt":"C'\u00e9tait il y a longtempsun jour o\u00f9 la fatigue n'engluait pas toutle rire doux du sable sous les piedsla m\u00e9lodie des lumi\u00e8resce vent affolantet je tournais au rythme lent des vaguesune danse pas si m\u00e9lancoliqueo\u00f9 mon corps aimait vivre l'instantce flou entre deux gravit\u00e9sd'apr\u00e8s le photoblog Pr\u00e9sence Urbaine - Mister\u2026","rel":"","context":"Dans &quot;photos&quot;","img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":985,"url":"http:\/\/www.xaviergalaup.net\/tikopia\/2010\/08\/je-vois-flou-2\/","url_meta":{"origin":963,"position":2},"title":"Je vois flou","date":"21 ao\u00fbt 2010","format":false,"excerpt":"C'\u00e9tait il y a longtempsun jour o\u00f9 la fatigue n'engluait pas toutle rire doux du sable sous les piedsla m\u00e9lodie des lumi\u00e8resce vent affolantet je tournais au rythme lent des vaguesune danse pas si m\u00e9lancoliqueo\u00f9 mon corps aimait vivre l'instantce flou entre deux gravit\u00e9sd'apr\u00e8s le photoblog Pr\u00e9sence Urbaine - Mister\u2026","rel":"","context":"Dans &quot;divers&quot;","img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":813,"url":"http:\/\/www.xaviergalaup.net\/tikopia\/2009\/01\/une-journee-faite-que-declats\/","url_meta":{"origin":963,"position":3},"title":"Une journ\u00e9e faite que d&rsquo;\u00e9clats","date":"27 janvier 2009","format":false,"excerpt":"Une journ\u00e9e faite que d'\u00e9clats n'apaise pas les questions.","rel":"","context":"Dans &quot;phrase du jour&quot;","img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":974,"url":"http:\/\/www.xaviergalaup.net\/tikopia\/2010\/06\/somme-doublis\/","url_meta":{"origin":963,"position":4},"title":"Somme d&rsquo;oublis","date":"13 juin 2010","format":false,"excerpt":"Les mouvements sont trop infimes pour retrouver le fil de ces r\u00eaves, j'ai tout oubli\u00e9 y compris o\u00f9 je suis, la fatigue me p\u00e8se tant et tant que je ne cherche plus \u00e0 me lever, j'ajoute heure apr\u00e8s heure du flou dans ma t\u00eate, joyeuses amn\u00e9sies vers cette \u00e9vanescence qui\u2026","rel":"","context":"Dans &quot;photos&quot;","img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":633,"url":"http:\/\/www.xaviergalaup.net\/tikopia\/2006\/06\/je-ne-suis-pas-flou\/","url_meta":{"origin":963,"position":5},"title":"Je ne suis pas flou","date":"8 juin 2006","format":false,"excerpt":"je r\u00eave, je fuis, je floue bleu, je ne suis pas fou, les t\u00e2ches blanches g\u00e2chent mon cerveau bleu qui flotte, j'imagine, je mange l'air, je m'immisce dans le bleu, je ne suis pas fou, les bruits de l'automobile cahotent dans mon cerveau m\u00e9tal qui brille, je cris, je vise,\u2026","rel":"","context":"Dans &quot;photos&quot;","img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/posts\/963"}],"collection":[{"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/comments?post=963"}],"version-history":[{"count":0,"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/posts\/963\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/media?parent=963"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/categories?post=963"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/tags?post=963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}