{"id":836,"date":"2009-02-19T18:27:56","date_gmt":"2009-02-19T18:27:56","guid":{"rendered":"http:\/\/tikopia.wordpress.com\/2009\/02\/19\/enfin-le-soleil-disparait-plus-tard\/"},"modified":"2009-02-19T18:27:56","modified_gmt":"2009-02-19T18:27:56","slug":"enfin-le-soleil-disparait-plus-tard","status":"publish","type":"post","link":"http:\/\/www.xaviergalaup.net\/tikopia\/2009\/02\/enfin-le-soleil-disparait-plus-tard\/","title":{"rendered":"enfin le soleil disparait plus tard"},"content":{"rendered":"<p>Enfin le soleil disparait plus tard, laissant plus de paix dans nos corps encore saisis par l&rsquo;hiver.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Enfin le soleil disparait plus tard, laissant plus de paix dans nos corps encore saisis par l&rsquo;hiver.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[20],"tags":[],"jetpack_featured_media_url":"","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5H0vD-du","jetpack-related-posts":[{"id":1568,"url":"http:\/\/www.xaviergalaup.net\/tikopia\/2012\/05\/je-suis-le-sud\/","url_meta":{"origin":836,"position":0},"title":"je suis le Sud","date":"17 mai 2012","format":false,"excerpt":"Sur un air de bandon\u00e9on on s\u2019est embrass\u00e9 pour la premi\u00e8re fois et pourtant nous a saisis la nostalgie d\u2019un amour qui prend fin la peur d\u2019un soleil qui ne se l\u00e8vera plus dans le Sud de notre enfance et pourtant on revient toujours \u00e0 ses premiers amours cette tristesse\u2026","rel":"","context":"Dans &quot;music&quot;","img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":724,"url":"http:\/\/www.xaviergalaup.net\/tikopia\/2007\/08\/gondolier-rupestre\/","url_meta":{"origin":836,"position":1},"title":"Gondolier rupestre","date":"30 ao\u00fbt 2007","format":false,"excerpt":"Je me prom\u00e8ne \u00e0 Venise comme dans une caverne pr\u00e9historique, on dirait les traces vivantes d'un monde en train de mourir, \u00e0 chaque coin de rue, je vois un masque decom\u00e9dia del'arte , j'entends d\u00e9clamer des po\u00e8mes tristes sur l'amour, plus loin un cort\u00e8ge fun\u00e8bre semble saisis d'une beaut\u00e9 romantique,\u2026","rel":"","context":"Dans &quot;photos&quot;","img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2015,"url":"http:\/\/www.xaviergalaup.net\/tikopia\/2012\/09\/photo-du-23-septembre-2012-le-funambule\/","url_meta":{"origin":836,"position":2},"title":"Photo du 23 septembre 2012: le funambule","date":"23 septembre 2012","format":false,"excerpt":"Il me fallait ce moment de l\u00e9g\u00e8ret\u00e9, imp\u00e9rativement, le seul de la semaine, la plage, la mer, le sable sous les pieds, le vent sur le torse, l\u2019apaisement de la nage, tout cela ne suffisait pas \u00e0 oublier, un quotidien vide de sensations, depuis longtemps je voulais m\u2019\u00e9lever sur un\u2026","rel":"","context":"Dans &quot;fragments d'une histoire&quot;","img":{"alt_text":"","src":"https:\/\/i2.wp.com\/ssl11.ovh.net\/~xaviergada\/tikopia\/wp-content\/uploads\/2012\/09\/Equilibriste.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":844,"url":"http:\/\/www.xaviergalaup.net\/tikopia\/2009\/02\/presque-le-printemps-des-sens\/","url_meta":{"origin":836,"position":3},"title":"Presque le printemps des sens","date":"27 f\u00e9vrier 2009","format":false,"excerpt":"Le beau temps apr\u00e8s l'hiver est la paix des sens, le corps qui revit, les yeux s'\u00e9largissent d'horizons chaleureux (ou presque), le cerveau se d\u00e9tend et croque toutes les perles des sensations, laisser aller la sensualit\u00e9 des ses et le calme des ambiances, les passants sont plus l\u00e9gers, les discussions\u2026","rel":"","context":"Dans &quot;divers&quot;","img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":871,"url":"http:\/\/www.xaviergalaup.net\/tikopia\/2009\/04\/histoire-urbaine\/","url_meta":{"origin":836,"position":4},"title":"Histoire urbaine","date":"10 avril 2009","format":false,"excerpt":"Je ne veux pas disparaitre comme ces silhouettes qui passent (et tr\u00e9passent?) devant mes yeux. Je marche, j'attends et je cherche une expression, un visage, un corps qui d\u00e9sire de la couleur. L'exub\u00e9rance architecturale me fait plus vibrer que le pas press\u00e9 des passants. Je photographie discr\u00e8tement \u00e0 la vol\u00e9e\u2026","rel":"","context":"Dans &quot;micro-fictions&quot;","img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":952,"url":"http:\/\/www.xaviergalaup.net\/tikopia\/2010\/01\/lire-en-automne\/","url_meta":{"origin":836,"position":5},"title":"Lire en automne","date":"24 janvier 2010","format":false,"excerpt":"Entre deux averses ce livre rongeait ma solitude, l'automne \u00e9tait ma p\u00e9riode f\u00e9tiche pour lire et vivre par cafard interpos\u00e9 cette nuit perp\u00e9tuel en moi, tenter de d\u00e9tromper le flot de questions affluant quand l'hiver emp\u00eachait les distractions ext\u00e9rieures, la bi\u00e8re d\u00e9goulinait dans ma torpeur pr\u00e8s d'un feu brulant, tisonn\u00e9\u2026","rel":"","context":"Dans &quot;micro-fictions&quot;","img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/posts\/836"}],"collection":[{"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/comments?post=836"}],"version-history":[{"count":0,"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/posts\/836\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/media?parent=836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/categories?post=836"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/tags?post=836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}