{"id":2154,"date":"2012-12-09T16:49:20","date_gmt":"2012-12-09T15:49:20","guid":{"rendered":"http:\/\/www.xaviergalaup.fr\/tikopia\/?p=2154"},"modified":"2012-12-09T16:49:20","modified_gmt":"2012-12-09T15:49:20","slug":"lheure-du-the","status":"publish","type":"post","link":"http:\/\/www.xaviergalaup.net\/tikopia\/2012\/12\/lheure-du-the\/","title":{"rendered":"l&rsquo;heure du th\u00e9"},"content":{"rendered":"<p><a href=\"https:\/\/ssl11.ovh.net\/~xaviergada\/tikopia\/wp-content\/uploads\/2012\/12\/gobelet-pivoineverte-2.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-2155\" title=\"Pivoine dans une tasse\" src=\"https:\/\/ssl11.ovh.net\/~xaviergada\/tikopia\/wp-content\/uploads\/2012\/12\/gobelet-pivoineverte-2-294x300.jpg\" alt=\"Pivoine dans une tasse calligraphi\u00e9e \u00e0 la japonaise\" width=\"294\" height=\"300\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">C\u2019est l\u2019heure du th\u00e9, j\u2019attends sa visite. Il r\u00e8gne un doux parfum de fleurs cr\u00e9ant un havre de paix alors qu\u2019il fait mauvais dehors. Je suis impatient qu\u2019elle arrive. Nos conversations futiles ou s\u00e9rieuses s\u2019enfilent comme un beau collier de perles. Elle a ses petits moments d\u2019absence, le regard pos\u00e9 sur un nuage. Elle a ses petits sourires enigmatiques lorsqu\u2019elle ne veut pas r\u00e9pondre \u00e0 l\u2019une de mes questions. Quand elle parle de son \u00e2ge et de son Alzheimer , elle balaie d\u2019un souffle mes d\u00e9n\u00e9gations. Il reste si peu de temps \u00e0 notre amour, j\u2019esp\u00e8re qu\u2019elle ne sera pas en retard.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>C\u2019est l\u2019heure du th\u00e9, j\u2019attends sa visite. Il r\u00e8gne un doux parfum de fleurs cr\u00e9ant un havre de paix alors qu\u2019il fait mauvais dehors. Je suis impatient qu\u2019elle arrive. Nos conversations futiles ou s\u00e9rieuses s\u2019enfilent comme un beau collier de perles. Elle a ses petits moments d\u2019absence, le regard pos\u00e9 sur un nuage. Elle a &hellip; <\/p>\n<p class=\"link-more\"><a href=\"http:\/\/www.xaviergalaup.net\/tikopia\/2012\/12\/lheure-du-the\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;l&rsquo;heure du th\u00e9&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"[blog d'\u00e9criture] l'heure du th\u00e9 http:\/\/wp.me\/p2GN6a-yK","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[2,6,8,14,29],"tags":[],"jetpack_featured_media_url":"","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5H0vD-yK","jetpack-related-posts":[{"id":1623,"url":"http:\/\/www.xaviergalaup.net\/tikopia\/2012\/06\/vases-communicants-elle-revait-quelle-revait-et-la-voila-qui-reve-encore\/","url_meta":{"origin":2154,"position":0},"title":"Vases communicants: Elle r\u00eavait qu&rsquo;elle r\u00eavait et la voil\u00e0 qui r\u00eave encore","date":"1 juin 2012","format":false,"excerpt":"Vase communicant avec WingsOfFlo Vases communiquants Elle r\u00eavait qu'elle r\u00eavait et la voil\u00e0 qui r\u00eave encore Son ventre se tort, elle est en sueur. Elle le cherche.. Elle avait entendu ce frottement dans la cuisine. Son pied l\u00e9ger glissant sur les tomettes fra\u00eeches, le tintement de la th\u00e9i\u00e8re contre la\u2026","rel":"","context":"Dans &quot;vases communicants&quot;","img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1484,"url":"http:\/\/www.xaviergalaup.net\/tikopia\/2012\/04\/photo-du-13-avril-2012\/","url_meta":{"origin":2154,"position":1},"title":"Photo du 13 avril 2012","date":"15 avril 2012","format":false,"excerpt":"C\u2019est le moment de l\u2019embrasser et l\u2019h\u00e9sitation est l\u00e0. Nous avons march\u00e9 dans la ville calme du dimanche. Nous avons parl\u00e9 du coll\u00e8ge, des copains et des derni\u00e8res vid\u00e9os vues sur le net. Les silences timides ne duraient pas. Chacun s\u2019employait, f\u00e9brile, \u00e0 \u00e9viter ces blancs. On se pla\u00eet et\u2026","rel":"","context":"Dans &quot;fragments d'une histoire&quot;","img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":907,"url":"http:\/\/www.xaviergalaup.net\/tikopia\/2009\/06\/trace-en-rouge-12-et-fin\/","url_meta":{"origin":2154,"position":2},"title":"Trac\u00e9 en rouge &#8211; 12 et fin","date":"9 juin 2009","format":false,"excerpt":"(...) dans sa t\u00eate son visage disparu oui inventer contre la douleur la fatigue son visage le visage surtout le sourire de celle qu\u2019il aime surtout les mots enfin et par dessous tout il imagine il r\u00eave il s\u2019extrait du rouge par dessus tout il r\u00eave des mots enfin des\u2026","rel":"","context":"Dans &quot;micro-fictions&quot;","img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":699,"url":"http:\/\/www.xaviergalaup.net\/tikopia\/2007\/05\/micro-fictions-4\/","url_meta":{"origin":2154,"position":3},"title":"Micro-fictions","date":"9 mai 2007","format":false,"excerpt":"1\/ Premier coup de soleil de l'ann\u00e9e Bris\u00e9 dans mon \u00e9lan laborieux par le franc beau temps d'aujourd'hui, je me suis assise sur un banc face au Rh\u00f4ne. Les gens marchaient tr\u00e8s vite comme des animaux fuyants quelque menace. Les voitures s'affolaient sur le boulevard, qui \u00e0 la recherche d'une\u2026","rel":"","context":"Dans &quot;micro-fictions&quot;","img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2044,"url":"http:\/\/www.xaviergalaup.net\/tikopia\/2012\/10\/photo-du-jour-07-octobre-2012-la-reveuse\/","url_meta":{"origin":2154,"position":4},"title":"Photo du jour 07 octobre 2012 &#8211; La r\u00eaveuse","date":"7 octobre 2012","format":false,"excerpt":"\u00e0 C\u00e9cile-Anne H. La r\u00eaveuse est assise dans son jardin. La r\u00eaveuse se rem\u00e9more le livre qu\u2019elle vient de terminer. Une ni\u00e8me variation sur l\u2019amour qui triomphe malgr\u00e9 les obstacles. La r\u00eaveuse attend les enfants qui rentrent bient\u00f4t de l\u2019\u00e9cole. Ce livre l\u2019a troubl\u00e9 plus qu\u2019elle ne l\u2019aurait imagin\u00e9 avec\u2026","rel":"","context":"Dans &quot;art postal&quot;","img":{"alt_text":"","src":"https:\/\/i1.wp.com\/www.xaviergalaup.fr\/tikopia\/wp-content\/uploads\/2012\/10\/r\u00c3\u00aaveuse-au-jardin064-1-212x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2665,"url":"http:\/\/www.xaviergalaup.net\/tikopia\/2019\/10\/jouir-avec-dostoievski\/","url_meta":{"origin":2154,"position":5},"title":"Jouir avec Dosto\u00efevski","date":"19 octobre 2019","format":false,"excerpt":"Il avait oubli\u00e9 de fermer sa fen\u00eatre \u00e0 la tomb\u00e9e de la nuit la plupart du temps ce n'est pas g\u00eanant il faut v\u00e9rifier si un scolopendre ou autre petite bestiole n'est pas venu se glisser dans le lit ou au pied du bureau la c'est l'invasion biannuelle des fourmis\u2026","rel":"","context":"Dans &quot;atelier f-bon&quot;","img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/posts\/2154"}],"collection":[{"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/comments?post=2154"}],"version-history":[{"count":0,"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/posts\/2154\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/media?parent=2154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/categories?post=2154"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.xaviergalaup.net\/tikopia\/wp-json\/wp\/v2\/tags?post=2154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}